{"id":897,"date":"2017-02-13T19:38:11","date_gmt":"2017-02-13T19:38:11","guid":{"rendered":"http:\/\/conagopareazuay.gob.ec\/w30\/?p=897"},"modified":"2017-02-13T19:38:11","modified_gmt":"2017-02-13T19:38:11","slug":"con-exito-se-desarrollo-seminario","status":"publish","type":"post","link":"https:\/\/conagopareazuay.gob.ec\/w30\/con-exito-se-desarrollo-seminario\/","title":{"rendered":"Con \u00c9xito Se Desarroll\u00f3 Seminario"},"content":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"https:\/\/www.hupso.com\/share\/\"><img decoding=\"async\" src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"facebook_send\");var hupso_counters_lang = \"es_LA\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Con%20%C3%89xito%20Se%20Desarroll%C3%B3%20Seminario\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div><p><img decoding=\"async\" class=\"size-medium wp-image-898 alignleft\" src=\"http:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/13-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/13-300x158.jpg 300w, https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/13-768x403.jpg 768w, https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/13-1024x538.jpg 1024w, https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/13.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Cerca de 100 participantes del Seminario Marco Jur\u00eddico del Ordenamiento Territorial analizaron la normativa jur\u00eddica b\u00e1sica relacionada con el ordenamiento territorial del pa\u00eds y la Ley para evitar la especulaci\u00f3n sobre el valor de las tierras, evento organizado por Conagopare Azuay el pasado viernes 10 de febrero en las instalaciones del complejo recreacional Planeta Azul del cant\u00f3n Gualaceo.<\/p>\n<p>Ren\u00e9 Lucero, presidente de la instancia organizativa parroquial asegura que este encuentro cont\u00f3 con el aval acad\u00e9mico del Colegio de Abogados del Azuay, se enmarca dentro de la planificaci\u00f3n institucional a trav\u00e9s de programa de capacitaci\u00f3n y fortalecimiento de capacidades y que este a\u00f1o a m\u00e1s de beneficiar a Presidentes, Vocales y t\u00e9cnicos de los gobiernos parroquiales del Azuay, incluy\u00f3 la participaci\u00f3n de profesionales a fines a la materia de otros gobiernos locales.<img decoding=\"async\" class=\"size-medium wp-image-899 alignright\" src=\"http:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/21-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/21-300x158.jpg 300w, https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/21-768x403.jpg 768w, https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/21-1024x538.jpg 1024w, https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/21.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>El seminario fue impartido por el reconocido jurista y actual presidente del Colegio de Abogados del Azuay, Carlos Castro Riera; entre los objetivos espec\u00edficos se contemplaron conocer las relaciones entre la organizaci\u00f3n territorial del Estado ecuatoriano y la organizaci\u00f3n general del Estado, conocer las relaciones entre el ordenamiento jur\u00eddico y el ordenamiento territorial ecuatoriano y conocer la normativa constitucional y legal b\u00e1sica aplicable al ordenamiento territorial parroquial.<\/p>\n<p><img decoding=\"async\" class=\"size-medium wp-image-900 alignleft\" src=\"http:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/15-300x158.jpg\" alt=\"\" width=\"300\" height=\"158\" srcset=\"https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/15-300x158.jpg 300w, https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/15-768x403.jpg 768w, https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/15-1024x538.jpg 1024w, https:\/\/conagopareazuay.gob.ec\/w30\/wp-content\/uploads\/2017\/02\/15.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>La capacitaci\u00f3n se desarroll\u00f3 a partir de las 08:00 hasta las 18:00 los contenidos fueron; el territorio y el ordenamiento jur\u00eddico, la normativa constitucional y civil del territorio, el COOTAD y la Ley Org\u00e1nica, uso y gesti\u00f3n del suelo, Leyes referentes al sistema nacional de \u00e1reas protegidas, desarrollo agrario y el ordenamiento territorial, Ley y reglamentos de caminos y la afectaci\u00f3n del uso del suelo y An\u00e1lisis de la Ley Org\u00e1nica para evitar la especulaci\u00f3n sobre el valor de las tierras; conocida como Ley de Plusval\u00eda.<\/p>\n<p><strong><em>M\u00e1s capacitaciones<\/em><\/strong><\/p>\n<p>Para la presente semana contin\u00faan los programas de capacitaci\u00f3n en Conagopare Azuay, informa Ren\u00e9 Lucero, es as\u00ed durante los d\u00edas mi\u00e9rcoles 15 y jueves 16 de febrero se desarrollar\u00e1 el Taller de Compras P\u00fablicas, en donde se abordar\u00e1n las tem\u00e1ticas Procesos de subasta inversa electr\u00f3nica y elaboraci\u00f3n de presupuestos referenciales de acuerdo a la codificaci\u00f3n y actualizaci\u00f3n de las resoluciones emitidas por el Servicio de Contrataci\u00f3n P\u00fablica.<\/p>\n<p>La actualizaci\u00f3n de conocimientos se desarrollar\u00e1 en dos grupos, el mi\u00e9rcoles 15 est\u00e1 destinado para las Juntas Parroquiales del cant\u00f3n Cuenca y las parroquias pertenecientes a la cuenca del Jubones, en tanto que el jueves 16 estar\u00e1n presentes las parroquias de los cantones pertenecientes a las cuencas del Santa B\u00e1rbara y Paute, est\u00e1 dirigido a los t\u00e9cnicos encargados del manejo del portal de compras p\u00fablicas de los gobiernos parroquiales y se realizar\u00e1 a partir de las 09:00 en la sala de capacitaci\u00f3n de Conagopare Azuay, puntualiz\u00f3 finalmente Lucero Mora.<\/p>\n","protected":false},"excerpt":{"rendered":"<div style=\"padding-bottom:20px; padding-top:10px;\" class=\"hupso-share-buttons\"><!-- Hupso Share Buttons - https:\/\/www.hupso.com\/share\/ --><a class=\"hupso_counters\" href=\"https:\/\/www.hupso.com\/share\/\"><img src=\"https:\/\/static.hupso.com\/share\/buttons\/lang\/es\/share-small.png\" style=\"border:0px; padding-top:2px; float:left;\" alt=\"Share Button\"\/><\/a><script type=\"text\/javascript\">var hupso_services_c=new Array(\"twitter\",\"facebook_like\",\"facebook_send\");var hupso_counters_lang = \"es_LA\";var hupso_image_folder_url = \"\";var hupso_url_c=\"\";var hupso_title_c=\"Con%20%C3%89xito%20Se%20Desarroll%C3%B3%20Seminario\";<\/script><script type=\"text\/javascript\" src=\"https:\/\/static.hupso.com\/share\/js\/counters.js\"><\/script><!-- Hupso Share Buttons --><\/div><p>Cerca de 100 participantes del Seminario Marco Jur\u00eddico del Ordenamiento Territorial analizaron la normativa jur\u00eddica b\u00e1sica relacionada con el ordenamiento territorial del pa\u00eds y la Ley para evitar la especulaci\u00f3n sobre el valor de las tierras, evento organizado por Conagopare Azuay el pasado viernes 10 de febrero en las instalaciones del complejo recreacional Planeta Azul [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-897","post","type-post","status-publish","format-standard","hentry","category-noticias","entry"],"_links":{"self":[{"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/posts\/897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/comments?post=897"}],"version-history":[{"count":1,"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/posts\/897\/revisions"}],"predecessor-version":[{"id":901,"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/posts\/897\/revisions\/901"}],"wp:attachment":[{"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/media?parent=897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/categories?post=897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conagopareazuay.gob.ec\/w30\/wp-json\/wp\/v2\/tags?post=897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}